{"id":8085,"date":"2026-02-24T08:55:49","date_gmt":"2026-02-24T07:55:49","guid":{"rendered":"https:\/\/www.lust-auf-muenchen.com\/?p=8085"},"modified":"2026-03-27T20:36:31","modified_gmt":"2026-03-27T19:36:31","slug":"fuehrung-durchs-westend-am-%f0%9f%97%93%ef%b8%8f-03-06-2026-um-%e2%8f%b0-1730-uhr","status":"publish","type":"post","link":"https:\/\/www.lust-auf-muenchen.com\/en\/fuehrung-durchs-westend-am-%f0%9f%97%93%ef%b8%8f-03-06-2026-um-%e2%8f%b0-1730-uhr\/","title":{"rendered":"Guided tour through the Westend on \ud83d\uddd3\ufe0f 03.06.2026 at \u23f0 17:30"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;4.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Entdeckungstour durch M\u00fcnchens vielf\u00e4ltiges Viertel<\/h2>\n<p><strong>Dauer ca. zwei Stunden<\/strong><\/p>\n<p><strong>Kosten: EUR 18 pro Person<\/strong><\/p>\n<p data-start=\"434\" data-end=\"721\"><em>Willkommen im Westend! Auf dieser Stadtf\u00fchrung entdecken wir eines der spannendsten und wandelbarsten Viertel M\u00fcnchens. Zwischen historischen Arbeitersiedlungen, imposanter Industriearchitektur und buntem multikulturellem Leben sp\u00fcren wir dem besonderen Charme der Schwanthalerh\u00f6he nach. <\/em><em>Unsere Tour beginnt auf der geschichtstr\u00e4chtigen Theresienh\u00f6he, wo heute moderne Architektur auf alte Messehallen trifft. Von hier aus tauchen wir ein in das Herz des Westends, vorbei an kleinen Hinterh\u00f6fen, versteckten Werkst\u00e4tten und gem\u00fctlichen Caf\u00e9s. Au\u00dferdem besuchen wir eine der ersten sozialen Einrichtungen der Sadt und lassen uns von imposanten Kirchenbauten der Jahrhundertwende um 1900 beeindrucken. Ob Geschichte, Alltagskultur oder Street Art \u2013 das Westend steckt voller \u00dcberraschungen. Die F\u00fchrung l\u00e4dt dazu ein, hinter die Fassaden zu blicken und die Geschichten der Menschen kennenzulernen, die dieses Viertel zu einem der lebendigsten Orte M\u00fcnchens machen.<\/em><\/p>\n<p>Anmeldung: Direkt \u00fcber eine <a href=\"https:\/\/www.lust-auf-muenchen.com\/kontakt\/#\">Mail an mich<\/a><\/p>\n<p>Ich freue mich, wenn Ihr mich auf meiner neuesten Stadtviertelf\u00fchrung begleitet!<\/p>\n<p>&nbsp;<br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entdeckungstour durch M\u00fcnchens vielf\u00e4ltiges Viertel Dauer ca. zwei Stunden Kosten: EUR 18 pro Person Willkommen im Westend! Auf dieser Stadtf\u00fchrung entdecken wir eines der spannendsten und wandelbarsten Viertel M\u00fcnchens. Zwischen historischen Arbeitersiedlungen, imposanter Industriearchitektur und buntem multikulturellem Leben sp\u00fcren wir dem besonderen Charme der Schwanthalerh\u00f6he nach. Unsere Tour beginnt auf der geschichtstr\u00e4chtigen Theresienh\u00f6he, wo heute [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"Haidhausen am 03.09.2020","_et_gb_content_width":"","footnotes":""},"categories":[11,12],"tags":[],"class_list":["post-8085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelle-touren","category-aktuelles"],"_links":{"self":[{"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/posts\/8085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/comments?post=8085"}],"version-history":[{"count":2,"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/posts\/8085\/revisions"}],"predecessor-version":[{"id":8087,"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/posts\/8085\/revisions\/8087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/media\/6548"}],"wp:attachment":[{"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/media?parent=8085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/categories?post=8085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lust-auf-muenchen.com\/en\/wp-json\/wp\/v2\/tags?post=8085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}